{"id":522,"count":6,"description":"","link":"https:\/\/agoodday.me\/ja\/category\/restaurants\/sushi\/","name":"\u5bff\u53f8","slug":"sushi","taxonomy":"category","parent":382,"meta":[],"_links":{"self":[{"href":"https:\/\/agoodday.me\/ja\/wp-json\/wp\/v2\/categories\/522","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/agoodday.me\/ja\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/agoodday.me\/ja\/wp-json\/wp\/v2\/taxonomies\/category"}],"up":[{"embeddable":true,"href":"https:\/\/agoodday.me\/ja\/wp-json\/wp\/v2\/categories\/382"}],"wp:post_type":[{"href":"https:\/\/agoodday.me\/ja\/wp-json\/wp\/v2\/posts?categories=522"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}