{"id":262,"count":5,"description":"","link":"https:\/\/agoodday.me\/en\/category\/restaurants\/bar\/","name":"Bar","slug":"bar","taxonomy":"category","parent":192,"meta":[],"_links":{"self":[{"href":"https:\/\/agoodday.me\/en\/wp-json\/wp\/v2\/categories\/262","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/agoodday.me\/en\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/agoodday.me\/en\/wp-json\/wp\/v2\/taxonomies\/category"}],"up":[{"embeddable":true,"href":"https:\/\/agoodday.me\/en\/wp-json\/wp\/v2\/categories\/192"}],"wp:post_type":[{"href":"https:\/\/agoodday.me\/en\/wp-json\/wp\/v2\/posts?categories=262"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}